{"id":121,"count":1,"description":"","link":"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/","name":"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34","slug":"%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Archives - menammechanika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.menammechanika.co.th\/th\/tag\/\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Archives - menammechanika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.menammechanika.co.th\/th\/tag\/\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\/\" \/>\n<meta property=\"og:site_name\" content=\"menammechanika\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/\",\"url\":\"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/\",\"name\":\"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Archives - menammechanika\",\"isPartOf\":{\"@id\":\"https:\/\/www.menammechanika.co.th\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/#breadcrumb\"},\"inLanguage\":\"th\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.menammechanika.co.th\/th\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.menammechanika.co.th\/#website\",\"url\":\"https:\/\/www.menammechanika.co.th\/\",\"name\":\"menammechanika\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.menammechanika.co.th\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.menammechanika.co.th\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.menammechanika.co.th\/#organization\",\"name\":\"Menam Mechanika\",\"url\":\"https:\/\/www.menammechanika.co.th\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.menammechanika.co.th\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.menammechanika.co.th\/wp-content\/uploads\/2024\/03\/cropped-MMK-logo-03.png\",\"contentUrl\":\"https:\/\/www.menammechanika.co.th\/wp-content\/uploads\/2024\/03\/cropped-MMK-logo-03.png\",\"width\":512,\"height\":512,\"caption\":\"Menam Mechanika\"},\"image\":{\"@id\":\"https:\/\/www.menammechanika.co.th\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Archives - menammechanika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.menammechanika.co.th\/th\/tag\/\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Archives - menammechanika","og_url":"https:\/\/www.menammechanika.co.th\/th\/tag\/\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34\/","og_site_name":"menammechanika","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/","url":"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/","name":"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Archives - menammechanika","isPartOf":{"@id":"https:\/\/www.menammechanika.co.th\/#website"},"breadcrumb":{"@id":"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/#breadcrumb"},"inLanguage":"th"},{"@type":"BreadcrumbList","@id":"https:\/\/www.menammechanika.co.th\/th\/tag\/%e0%b8%ab%e0%b8%b8%e0%b9%88%e0%b8%99%e0%b8%a2%e0%b8%99%e0%b8%95%e0%b9%8c%e0%b9%81%e0%b8%82%e0%b8%99%e0%b8%81%e0%b8%a5%e0%b8%ad%e0%b8%b1%e0%b8%95%e0%b9%82%e0%b8%99%e0%b8%a1%e0%b8%b1%e0%b8%95%e0%b8%b4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.menammechanika.co.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c\u0e41\u0e02\u0e19\u0e01\u0e25\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34"}]},{"@type":"WebSite","@id":"https:\/\/www.menammechanika.co.th\/#website","url":"https:\/\/www.menammechanika.co.th\/","name":"menammechanika","description":"","publisher":{"@id":"https:\/\/www.menammechanika.co.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.menammechanika.co.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.menammechanika.co.th\/#organization","name":"Menam Mechanika","url":"https:\/\/www.menammechanika.co.th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.menammechanika.co.th\/#\/schema\/logo\/image\/","url":"https:\/\/www.menammechanika.co.th\/wp-content\/uploads\/2024\/03\/cropped-MMK-logo-03.png","contentUrl":"https:\/\/www.menammechanika.co.th\/wp-content\/uploads\/2024\/03\/cropped-MMK-logo-03.png","width":512,"height":512,"caption":"Menam Mechanika"},"image":{"@id":"https:\/\/www.menammechanika.co.th\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.menammechanika.co.th\/th\/wp-json\/wp\/v2\/tags\/121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.menammechanika.co.th\/th\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.menammechanika.co.th\/th\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.menammechanika.co.th\/th\/wp-json\/wp\/v2\/posts?tags=121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}